{"id":139,"count":11,"description":"","link":"https:\/\/constantinianorder.com\/en\/category\/news\/news-from-delegations\/delegations-of-italy\/delegation-of-liguria\/","name":"Delegation of Liguria","slug":"delegation-of-liguria","taxonomy":"category","parent":107,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Delegation of Liguria Archivi - Sacro Militare Ordine Costantiniano di San Giorgio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/constantinianorder.com\/en\/category\/news\/news-from-delegations\/delegations-of-italy\/delegation-of-liguria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Delegation of Liguria Archivi - Sacro Militare Ordine Costantiniano di San Giorgio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/constantinianorder.com\/en\/category\/news\/news-from-delegations\/delegations-of-italy\/delegation-of-liguria\/\" \/>\n<meta property=\"og:site_name\" content=\"Sacro Militare Ordine Costantiniano di San Giorgio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/constantinianorder.com\/en\/category\/news\/news-from-delegations\/delegations-of-italy\/delegation-of-liguria\/\",\"url\":\"https:\/\/constantinianorder.com\/en\/category\/news\/news-from-delegations\/delegations-of-italy\/delegation-of-liguria\/\",\"name\":\"Delegation of Liguria Archivi - Sacro Militare Ordine Costantiniano di San Giorgio\",\"isPartOf\":{\"@id\":\"https:\/\/constantinianorder.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/constantinianorder.com\/en\/category\/news\/news-from-delegations\/delegations-of-italy\/delegation-of-liguria\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/constantinianorder.com\/en\/category\/news\/news-from-delegations\/delegations-of-italy\/delegation-of-liguria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/constantinianorder.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/constantinianorder.com\/en\/category\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"News from Delegations\",\"item\":\"https:\/\/constantinianorder.com\/en\/category\/news\/news-from-delegations\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Delegations of Italy\",\"item\":\"https:\/\/constantinianorder.com\/en\/category\/news\/news-from-delegations\/delegations-of-italy\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Delegation of Liguria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/constantinianorder.com\/#website\",\"url\":\"https:\/\/constantinianorder.com\/\",\"name\":\"Sacro Militare Ordine Costantiniano di San Giorgio\",\"description\":\"Ordine Ufficiale\",\"publisher\":{\"@id\":\"https:\/\/constantinianorder.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/constantinianorder.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/constantinianorder.com\/#organization\",\"name\":\"Sacro Militare Ordine Costantiniano di San Giorgio\",\"url\":\"https:\/\/constantinianorder.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/constantinianorder.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/constantinianorder.com\/wp-content\/uploads\/2025\/10\/cropped-logo-costantiniano.png\",\"contentUrl\":\"https:\/\/constantinianorder.com\/wp-content\/uploads\/2025\/10\/cropped-logo-costantiniano.png\",\"width\":512,\"height\":512,\"caption\":\"Sacro Militare Ordine Costantiniano di San Giorgio\"},\"image\":{\"@id\":\"https:\/\/constantinianorder.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/constantinianorder\",\"https:\/\/www.instagram.com\/constantinianorder\/\",\"https:\/\/www.youtube.com\/@granmagisterodelsacromilit9375\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Delegation of Liguria Archivi - Sacro Militare Ordine Costantiniano di San Giorgio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/constantinianorder.com\/en\/category\/news\/news-from-delegations\/delegations-of-italy\/delegation-of-liguria\/","og_locale":"en_US","og_type":"article","og_title":"Delegation of Liguria Archivi - Sacro Militare Ordine Costantiniano di San Giorgio","og_url":"https:\/\/constantinianorder.com\/en\/category\/news\/news-from-delegations\/delegations-of-italy\/delegation-of-liguria\/","og_site_name":"Sacro Militare Ordine Costantiniano di San Giorgio","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/constantinianorder.com\/en\/category\/news\/news-from-delegations\/delegations-of-italy\/delegation-of-liguria\/","url":"https:\/\/constantinianorder.com\/en\/category\/news\/news-from-delegations\/delegations-of-italy\/delegation-of-liguria\/","name":"Delegation of Liguria Archivi - Sacro Militare Ordine Costantiniano di San Giorgio","isPartOf":{"@id":"https:\/\/constantinianorder.com\/#website"},"breadcrumb":{"@id":"https:\/\/constantinianorder.com\/en\/category\/news\/news-from-delegations\/delegations-of-italy\/delegation-of-liguria\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/constantinianorder.com\/en\/category\/news\/news-from-delegations\/delegations-of-italy\/delegation-of-liguria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/constantinianorder.com\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/constantinianorder.com\/en\/category\/news\/"},{"@type":"ListItem","position":3,"name":"News from Delegations","item":"https:\/\/constantinianorder.com\/en\/category\/news\/news-from-delegations\/"},{"@type":"ListItem","position":4,"name":"Delegations of Italy","item":"https:\/\/constantinianorder.com\/en\/category\/news\/news-from-delegations\/delegations-of-italy\/"},{"@type":"ListItem","position":5,"name":"Delegation of Liguria"}]},{"@type":"WebSite","@id":"https:\/\/constantinianorder.com\/#website","url":"https:\/\/constantinianorder.com\/","name":"Sacro Militare Ordine Costantiniano di San Giorgio","description":"Ordine Ufficiale","publisher":{"@id":"https:\/\/constantinianorder.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/constantinianorder.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/constantinianorder.com\/#organization","name":"Sacro Militare Ordine Costantiniano di San Giorgio","url":"https:\/\/constantinianorder.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/constantinianorder.com\/#\/schema\/logo\/image\/","url":"https:\/\/constantinianorder.com\/wp-content\/uploads\/2025\/10\/cropped-logo-costantiniano.png","contentUrl":"https:\/\/constantinianorder.com\/wp-content\/uploads\/2025\/10\/cropped-logo-costantiniano.png","width":512,"height":512,"caption":"Sacro Militare Ordine Costantiniano di San Giorgio"},"image":{"@id":"https:\/\/constantinianorder.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/constantinianorder","https:\/\/www.instagram.com\/constantinianorder\/","https:\/\/www.youtube.com\/@granmagisterodelsacromilit9375"]}]}},"_links":{"self":[{"href":"https:\/\/constantinianorder.com\/en\/wp-json\/wp\/v2\/categories\/139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/constantinianorder.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/constantinianorder.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/constantinianorder.com\/en\/wp-json\/wp\/v2\/categories\/107"}],"wp:post_type":[{"href":"https:\/\/constantinianorder.com\/en\/wp-json\/wp\/v2\/posts?categories=139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}